{"id":23112,"date":"2022-11-08T01:29:41","date_gmt":"2022-11-07T23:29:41","guid":{"rendered":"https:\/\/vista-pro.com\/?p=23112"},"modified":"2023-05-20T21:26:31","modified_gmt":"2023-05-20T19:26:31","slug":"stanzia-vinella-in-motovun-istria-croatia-real-estate","status":"publish","type":"post","link":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/","title":{"rendered":"Stanzia Vinella in Motovun"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"23112\" class=\"elementor elementor-23112\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cf2cc17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cf2cc17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38a2ddd0\" data-id=\"38a2ddd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4dfe9b4e elementor-widget elementor-widget-text-editor\" data-id=\"4dfe9b4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 35%;\"><div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_23112\" class=\"pvc_stats total_only  pvc_load_by_ajax_update\" data-element-id=\"23112\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Wird geladen\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif?strip=all&quality=70&webp=70&avif=70&sharp=1&resize=16%2C16\" border=\"0\" \/><\/p><div class=\"pvc_clear\"><\/div><\/td>\n<td style=\"width: 65%; text-align: right;\"><div class=\"simplesocialbuttons simplesocial-round-icon simplesocialbuttons_inline simplesocialbuttons-align-right simplesocialbuttons-inline-no-animation\">\n<button class=\"simplesocial-msng-share\"  rel=\"nofollow\"  target=\"_blank\"  aria-label=\"Facebook Messenger-Teilen\" onclick=\"javascript:window.open( this.dataset.href, '_blank',  'menubar=no,toolbar=no,resizable=yes,scrollbars=yes,height=600,width=600' );return false;\" data-href=\"http:\/\/www.facebook.com\/dialog\/send?app_id=891268654262273&#038;redirect_uri=https%3A%2F%2Fwww.vista-pro.com%2Fde%2Fstanzia-vinella-in-motovun-istria-croatia-real-estate%2F&#038;link=https%3A%2F%2Fwww.vista-pro.com%2Fde%2Fstanzia-vinella-in-motovun-istria-croatia-real-estate%2F&#038;display=popup\" ><span class=\"simplesocialtxt\">Bote<\/span><\/button> \n<button onclick=\"javascript:window.open(this.dataset.href, '_blank' );return false;\" class=\"simplesocial-whatsapp-share\"  rel=\"nofollow\"  target=\"_blank\"  aria-label=\"WhatsApp-Teilen\" data-href=\"https:\/\/api.whatsapp.com\/send?text=https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/\"><span class=\"simplesocialtxt\">Whatsapp<\/span><\/button>\n<button onclick=\"javascript:window.open(this.dataset.href, '_self' );return false;\" class=\"simplesocial-viber-share\"  rel=\"nofollow\"  target=\"_blank\"  aria-label=\"Viber-Freigabe\" data-href=\"viber:\/\/forward?text=https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/\"><span class=\"simplesocialtxt\">Viber<\/span><\/button>\n<button onclick=\"javascript:window.location.href = this.dataset.href;return false;\" class=\"simplesocial-email-share\" aria-label=\"Per E-Mail teilen\"  rel=\"nofollow\"  target=\"_blank\"   data-href=\"mailto:?subject=Stanzia Vinella in Motovun&#038;body=https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/\"><span class=\"simplesocialtxt\">Email<\/span><\/button>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\"><span style=\"text-align: justify;\">V\u00f6llig abgeschiedenes luxuri\u00f6ses Anwesen in der N\u00e4he von Motovun mit 60.000 m\u00b2 gro\u00dfem Grundst\u00fcck. Das Bauernhaus stammt aus dem Jahr 1614 und wurde zwischen 2019 und 2021 tadellos restauriert. Etwa 460 m\u00b2 Wohnfl\u00e4che mit 5 Schlafzimmern, separatem Studio, Poolhaus mit Sommerk\u00fcche und 14 x 5 m Infinity-Salzwasserpool. Atemberaubende Aussicht auf die Festungsstadt Motovun, Weinberge, Olivenhaine und Tr\u00fcffelw\u00e4lder.<\/span><\/p>\n<div class=\"_178zopn\">\n<p><strong>Der Raum<\/strong><\/p>\n<p style=\"text-align: justify;\">Ger\u00e4umiges Bauernhaus aus Stein aus dem fr\u00fchen 17. Jahrhundert. Makellos restauriert mit honigfarbenem Stein, antiken Eichenbalken, Cotto-Fliesen und \u00d6ko-Farben auf Kalkbasis. F\u00fcnf elegante Schlafzimmer mit en-suite Badezimmern. Zwei Wohnzimmer mit sichtbaren Eichenbalken und Kamin. Bescheidener Luxus mit nat\u00fcrlichen Materialien, antiken M\u00f6beln, Beleuchtung und Kunst aus Asien und Afrika. Separates Studio mit K\u00fcchenzeile. Umfangreiche \u00fcberdachte Terrasse mit Esstisch f\u00fcr 10 Personen und Lounges. Poolhaus mit Badezimmer und Sommerk\u00fcche, Esstisch f\u00fcr 10 Personen und Sofas. Meerwasser-Infinity-Pool 14\u00d75 m mit atemberaubendem Blick auf Motovun.<\/p>\n<\/div>\n<div class=\"_178zopn\">\n<div>\n<hr>\n<\/div>\n<div>\n<p><br><\/p>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-9af484a e-flex e-con-boxed e-con e-parent\" data-id=\"9af484a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50ae17f gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"50ae17f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-23112 gallery-columns-1 gallery-size-2048x2048'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-001\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMTUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTAwMS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-001\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-001.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-004\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMTYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTAwNC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-004\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-004.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-006\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMTcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTAwNi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-006\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-006.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-013\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMTgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTAxMy5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-013\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-013.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-017\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMTksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTAxNy5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-017\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-020\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMjAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTAyMC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-020\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-020.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-022\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMjEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTAyMi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-022\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-022.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-026\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMjIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTAyNi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-026\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-026.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-029\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMjMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTAyOS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-029\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-029.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-030\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMjQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTAzMC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-030\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-030.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-033\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMjUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTAzMy5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-033\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-033.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-040\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMjYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA0MC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-040\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-040.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-041\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMjcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA0MS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-041\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-041.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-043\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMjgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA0My5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-043\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-043.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-047\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMjksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA0Ny5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-047\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-047.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-051\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMzAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA1MS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-051\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-051.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-056\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMzEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA1Ni5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-056\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-056.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-062\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMzIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA2Mi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-062\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-062.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-064\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMzMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA2NC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-064\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-064.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-065\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMzQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA2NS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-065\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-065.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-074\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMzUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA3NC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-074\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-074.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-088\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMzYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA4OC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-088\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-088.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-091\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMzcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA5MS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-091\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-091.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-092\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMzgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA5Mi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-092\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-092.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-095\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxMzksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA5NS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-095\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-095.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-098\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNDAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTA5OC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-098\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-098.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-100\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNDEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTEwMC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-100\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-100.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-108\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNDIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTEwOC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-108\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-108.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-109\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNDMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTEwOS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-109\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-112\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNDQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTExMi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-112\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-112.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-114\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNDUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTExNC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-114\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-114.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-117\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNDYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTExNy5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-117\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-127\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNDcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTEyNy5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-127\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-127.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-129\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNDgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTEyOS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-129\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-134\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNDksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTEzNC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-134\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-134.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-137\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNTAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTEzNy5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-137\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-141\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNTEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE0MS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-141\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-142\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNTIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE0Mi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-142\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-142.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-146\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNTMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE0Ni5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-146\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-146.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-147\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNTQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE0Ny5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-147\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-147.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-160\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNTUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE2MC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-160\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-160.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-161\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNTYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE2MS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-161\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-161.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-163\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNTcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE2My5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-163\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-163.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-171\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNTgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE3MS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-171\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-171.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-174\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNTksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE3NC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-174\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-174.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-176\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNjAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE3Ni5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-176\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-176.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-178\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNjEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE3OC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-178\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-178.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-180\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNjIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE4MC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-180\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-182\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNjMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE4Mi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-182\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-182.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-194\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNjQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTE5NC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-194\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-194.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-201\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNjUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTIwMS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-201\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-204\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNjYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTIwNC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-204\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-204.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-209\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNjcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTIwOS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-209\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-209.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-214\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNjgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTIxNC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-214\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-214.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-219\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNjksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTIxOS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-219\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-219.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-223\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNzAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTIyMy5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-223\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-223.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-231\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNzEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTIzMS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-231\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-231.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-233\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNzIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTIzMy5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-233\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-233.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-237\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNzMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTIzNy5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-237\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-237.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-243\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNzQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI0My5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-243\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-243.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-247\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNzUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI0Ny5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-247\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-247.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-255\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNzYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI1NS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-255\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-255.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-259\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNzcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI1OS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-259\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-259.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-260\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNzgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI2MC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-260\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-260.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-262\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxNzksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI2Mi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-262\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-262.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-263\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxODAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI2My5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-263\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-263.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-265\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxODEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI2NS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-265\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-265.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-266\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxODIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI2Ni5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-266\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-266.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-268\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxODMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI2OC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-268\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-268.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-269\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxODQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI2OS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-269\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-269.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-272\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxODUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI3Mi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-272\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-272.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-286\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxODYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI4Ni5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-286\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-286.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-291\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxODcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI5MS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-291\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-291.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-294\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxODgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI5NC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-294\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-294.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-295\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxODksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTI5NS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-295\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-295.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-300\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxOTAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTMwMC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-300\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-300.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-301\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxOTEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTMwMS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-301\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-301.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-302\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxOTIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTMwMi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-302\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-302.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-309\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxOTMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTMwOS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-309\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-309.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-316\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxOTQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTMxNi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-316\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-316.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-318\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxOTUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTMxOC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-318\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-318.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-341\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxOTYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTM0MS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-341\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-341.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-343\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxOTcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTM0My5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-343\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-343.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-344\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxOTgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTM0NC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-344\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-344.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-348\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMxOTksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTM0OC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-348\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-348.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-349\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMDAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTM0OS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-349\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-349.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-352\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMDEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTM1Mi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-352\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-352.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-357\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMDIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTM1Ny5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-357\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-357.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-358\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMDMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTM1OC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-358\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-358.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-363\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMDQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTM2My5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-363\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-363.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-369\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMDUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTM2OS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-369\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-369.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-373\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMDYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTM3My5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-373\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-373.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-374\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMDcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTM3NC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-374\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-374.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-376\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMDgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTM3Ni5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-376\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-376.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-400\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMDksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTQwMC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-400\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-400.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-425\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMTAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTQyNS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-425\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-425.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-429\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMTEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTQyOS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-429\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-429.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-432\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMTIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTQzMi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-432\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-432.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-436\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMTMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTQzNi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-436\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-436.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-437\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMTQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTQzNy5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-437\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-437.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-440\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMTUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTQ0MC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-440\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-440.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-481\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMTYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTQ4MS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-481\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-481.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-686\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMTcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTY4Ni5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-686\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-686.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-688\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMTgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTY4OC5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-688\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-688.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-692\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMTksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTY5Mi5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-692\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-692.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-696\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMjAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTY5Ni5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-696\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-696.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-699\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMjEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTY5OS5qcGciLCJzbGlkZXNob3ciOiI1MGFlMTdmIn0%3D\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-699\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-699.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6104\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMjIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxMDQuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6104\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6104.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6105\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMjMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxMDUuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6105\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6105.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6109\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMjQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxMDkuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6109\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6109.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6110\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMjUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxMTAuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6110\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6110.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6115\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMjYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxMTUuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6115\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2161w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6115.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6117\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMjcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxMTcuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6117\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2161w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6117.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6120\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMjgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxMjAuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6120\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2161w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6120.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6121\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMjksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxMjEuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6121\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2161w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6121.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6129\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMzAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxMjkuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6129\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6129.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6135\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMzEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxMzUuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6135\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6135.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6137\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMzIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxMzcuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6137\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6137.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6140\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMzMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxNDAuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6140\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6140.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6141\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMzQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxNDEuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6141\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6141.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6143\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMzUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxNDMuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6143\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6143.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6144\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMzYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxNDQuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6144\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6144.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6151\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMzcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxNTEuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6151\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6151.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6152\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMzgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxNTIuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6152\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6153\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMzksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxNTMuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6153\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6153.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6154\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNDAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxNTQuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6154\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6154.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6155\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNDEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxNTUuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6155\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6155.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6156\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNDIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxNTYuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6156\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6156.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6159\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNDMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxNTkuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6159\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6159.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6170\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNDQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxNzAuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6170\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2161w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6170.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6180\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNDUsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxODAuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6180\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6180.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6181\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNDYsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxODEuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6181\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 960w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181-480x720.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 480w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181-853x1280.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 853w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181-768x1152.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181-8x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 8w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181-400x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 400w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181-496x744.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=96 96w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=192 192w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=288 288w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=576 576w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6181.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=672 672w\" sizes=\"(max-width: 960px) 100vw, 960px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6190\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNDcsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYxOTAuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6190\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6190.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6201\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNDgsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYyMDEuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6201\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6201.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6205\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNDksInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYyMDUuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6205\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6205.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6207\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNTAsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYyMDcuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6207\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6207.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6211\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNTEsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYyMTEuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6211\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6211.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6212\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNTIsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYyMTIuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6212\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6212.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6218\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNTMsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYyMTguanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6218\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6218.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50ae17f\" data-elementor-lightbox-title=\"stanzia-vinella-motovun-istria-croatia-real-estate-6221\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNTQsInVybCI6Imh0dHBzOlwvXC93d3cudmlzdGEtcHJvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL3N0YW56aWEtdmluZWxsYS1tb3RvdnVuLWlzdHJpYS1jcm9hdGlhLXJlYWwtZXN0YXRlLTYyMjEuanBnIiwic2xpZGVzaG93IjoiNTBhZTE3ZiJ9\" title=\"stanzia-vinella-motovun-istrien-kroatien-immobilien-6221\"  href='https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1&w=2560'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;fit=2048%2C1365\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2160w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221-720x480.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 720w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221-1280x853.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1280w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221-768x512.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 768w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221-1536x1024.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 1536w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221-2048x1365.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 2048w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221-18x12.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 18w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221-900x600.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 900w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221-496x331.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1 496w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=216 216w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=432 432w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=648 648w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1080 1080w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1728 1728w, https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-6221.jpg?strip=all&amp;quality=70&amp;webp=70&amp;avif=70&amp;sharp=1&amp;w=1944 1944w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" title=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Completely secluded luxurious estate near Motovun with 60.000 m\u00b2 grounds. The farmhouse dates back to 1614 and was impeccably restored between 2019-2021. About 460 m\u00b2 living area with 5 bedrooms, seperate stuido, pool house with summer kitchen, and 14x5m infinity salt water pool. Breathtaking view on the fortress town Motovun, vineyards, olive groves and truffle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23119,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[381,357,384],"tags":[380,360,382,392],"class_list":["post-23112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-architecture","category-istria","category-motovun","tag-architecture","tag-istria","tag-motovun","tag-stanzia-vinella"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Completely secluded luxurious estate near Motovun with 60.000 m\u00b2 grounds. The farmhouse dates back to 1614 and was impeccably restored between 2019-2021.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Vista Pro\"\/>\n\t<meta name=\"google-site-verification\" content=\"4oFqZzmLWcyWIMy4eA-JPvOMpUyQMlWKGExznAh2ivE\" \/>\n\t<meta name=\"msvalidate.01\" content=\"ce086a5b504f44708dc7e1183b682878\" \/>\n\t<meta name=\"yandex-verification\" content=\"6797e2747f288a3d\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Vista Pro | Real Estate Istria\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Stanzia Vinella in Motovun | Vista Pro | Real Estate Istria\" \/>\n\t\t<meta property=\"og:description\" content=\"Completely secluded luxurious estate near Motovun with 60.000 m\u00b2 grounds. The farmhouse dates back to 1614 and was impeccably restored between 2019-2021.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/\" \/>\n\t\t<meta property=\"fb:app_id\" content=\"251215160915905\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t\t<meta property=\"article:section\" content=\"Architecture\" \/>\n\t\t<meta property=\"article:tag\" content=\"architecture\" \/>\n\t\t<meta property=\"article:tag\" content=\"istria\" \/>\n\t\t<meta property=\"article:tag\" content=\"motovun\" \/>\n\t\t<meta property=\"article:tag\" content=\"stanzia vinella\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-11-07T23:29:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-20T19:26:31+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/vistapronetwork\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@vistapronetwork\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Stanzia Vinella in Motovun | Vista Pro | Real Estate Istria\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Completely secluded luxurious estate near Motovun with 60.000 m\u00b2 grounds. The farmhouse dates back to 1614 and was impeccably restored between 2019-2021.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@vistapronetwork\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Vista Pro\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesedauer\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 Minute\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/stanzia-vinella-in-motovun-istria-croatia-real-estate\\\/#article\",\"name\":\"Stanzia Vinella in Motovun | Vista Pro | Real Estate Istria\",\"headline\":\"Stanzia Vinella in Motovun\",\"author\":{\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/author\\\/vista-pro\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.vista-pro.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1\",\"width\":2160,\"height\":1440},\"datePublished\":\"2022-11-08T01:29:41+02:00\",\"dateModified\":\"2023-05-20T21:26:31+02:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/stanzia-vinella-in-motovun-istria-croatia-real-estate\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/stanzia-vinella-in-motovun-istria-croatia-real-estate\\\/#webpage\"},\"articleSection\":\"Architecture, Istria, Motovun, Architecture, Istria, Motovun, Stanzia Vinella\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/stanzia-vinella-in-motovun-istria-croatia-real-estate\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vista-pro.com\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/category\\\/istria\\\/#listItem\",\"name\":\"Istria\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/category\\\/istria\\\/#listItem\",\"position\":2,\"name\":\"Istria\",\"item\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/category\\\/istria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/category\\\/istria\\\/motovun\\\/#listItem\",\"name\":\"Motovun\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/category\\\/istria\\\/motovun\\\/#listItem\",\"position\":3,\"name\":\"Motovun\",\"item\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/category\\\/istria\\\/motovun\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/stanzia-vinella-in-motovun-istria-croatia-real-estate\\\/#listItem\",\"name\":\"Stanzia Vinella in Motovun\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/category\\\/istria\\\/#listItem\",\"name\":\"Istria\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/stanzia-vinella-in-motovun-istria-croatia-real-estate\\\/#listItem\",\"position\":4,\"name\":\"Stanzia Vinella in Motovun\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/category\\\/istria\\\/motovun\\\/#listItem\",\"name\":\"Motovun\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/#organization\",\"name\":\"Vista Pro Network | Real Estate | Istria | Umag Buje Novigrad Porec Rovinj\",\"description\":\"Vista Pro Network | Real Estate | Istria | Umag Buje Novigrad Porec Rovinj\",\"url\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/\",\"email\":\"info@vista-pro.com\",\"telephone\":\"+385915127282\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/vista-pro.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-b.png\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/stanzia-vinella-in-motovun-istria-croatia-real-estate\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/stanzia-vinella-in-motovun-istria-croatia-real-estate\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/vistapronetwork\",\"https:\\\/\\\/x.com\\\/vistapronetwork\",\"https:\\\/\\\/instagram.com\\\/vistapronetwork\",\"https:\\\/\\\/pinterest.com\\\/vistapronetwork\",\"https:\\\/\\\/youtube.com\\\/@vistapronetwork\",\"https:\\\/\\\/linkedin.com\\\/in\\\/vistapronetwork\"],\"address\":{\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"Vladimir Nazor 5\",\"postalCode\":\"52470\",\"addressLocality\":\"Umag\",\"addressRegion\":\"Istria\",\"addressCountry\":\"HR\"},\"vatID\":\"HR30117654631\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/author\\\/vista-pro\\\/#author\",\"url\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/author\\\/vista-pro\\\/\",\"name\":\"Vista Pro\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/stanzia-vinella-in-motovun-istria-croatia-real-estate\\\/#webpage\",\"url\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/stanzia-vinella-in-motovun-istria-croatia-real-estate\\\/\",\"name\":\"Stanzia Vinella in Motovun | Vista Pro | Real Estate Istria\",\"description\":\"Completely secluded luxurious estate near Motovun with 60.000 m\\u00b2 grounds. The farmhouse dates back to 1614 and was impeccably restored between 2019-2021.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/stanzia-vinella-in-motovun-istria-croatia-real-estate\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/author\\\/vista-pro\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/author\\\/vista-pro\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.vista-pro.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/stanzia-vinella-in-motovun-istria-croatia-real-estate\\\/#mainImage\",\"width\":2160,\"height\":1440},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/stanzia-vinella-in-motovun-istria-croatia-real-estate\\\/#mainImage\"},\"datePublished\":\"2022-11-08T01:29:41+02:00\",\"dateModified\":\"2023-05-20T21:26:31+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/\",\"name\":\"Vista Pro | Real Estate Istria\",\"alternateName\":\"Vista Pro Network | Real Estate\",\"description\":\"Vista Pro Network | Real Estate | Istria | Umag Buje Novigrad Porec Rovinj\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vista-pro.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Stanzia Vinella in Motovun | Vista Pro | Real Estate Istria<\/title>\n\n","aioseo_head_json":{"title":"Stanzia Vinella in Motovun | VistaPro | Immobilien Istrien","description":"V\u00f6llig abgeschiedenes luxuri\u00f6ses Anwesen in der N\u00e4he von Motovun mit 60.000 m\u00b2 gro\u00dfem Grundst\u00fcck. Das Bauernhaus stammt aus dem Jahr 1614 und wurde zwischen 2019 und 2021 tadellos restauriert.","canonical_url":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"4oFqZzmLWcyWIMy4eA-JPvOMpUyQMlWKGExznAh2ivE","msvalidate.01":"ce086a5b504f44708dc7e1183b682878","yandex-verification":"6797e2747f288a3d","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/#article","name":"Stanzia Vinella in Motovun | Vista Pro | Real Estate Istria","headline":"Stanzia Vinella in Motovun","author":{"@id":"https:\/\/www.vista-pro.com\/de\/author\/vista-pro\/#author"},"publisher":{"@id":"https:\/\/www.vista-pro.com\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1","width":2160,"height":1440},"datePublished":"2022-11-08T01:29:41+02:00","dateModified":"2023-05-20T21:26:31+02:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/#webpage"},"isPartOf":{"@id":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/#webpage"},"articleSection":"Architecture, Istria, Motovun, Architecture, Istria, Motovun, Stanzia Vinella"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.vista-pro.com\/de#listItem","position":1,"name":"Home","item":"https:\/\/www.vista-pro.com\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/www.vista-pro.com\/de\/category\/istria\/#listItem","name":"Istria"}},{"@type":"ListItem","@id":"https:\/\/www.vista-pro.com\/de\/category\/istria\/#listItem","position":2,"name":"Istria","item":"https:\/\/www.vista-pro.com\/de\/category\/istria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.vista-pro.com\/de\/category\/istria\/motovun\/#listItem","name":"Motovun"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.vista-pro.com\/de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.vista-pro.com\/de\/category\/istria\/motovun\/#listItem","position":3,"name":"Motovun","item":"https:\/\/www.vista-pro.com\/de\/category\/istria\/motovun\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/#listItem","name":"Stanzia Vinella in Motovun"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.vista-pro.com\/de\/category\/istria\/#listItem","name":"Istria"}},{"@type":"ListItem","@id":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/#listItem","position":4,"name":"Stanzia Vinella in Motovun","previousItem":{"@type":"ListItem","@id":"https:\/\/www.vista-pro.com\/de\/category\/istria\/motovun\/#listItem","name":"Motovun"}}]},{"@type":"Organization","@id":"https:\/\/www.vista-pro.com\/de\/#organization","name":"Vista Pro Network | Real Estate | Istria | Umag Buje Novigrad Porec Rovinj","description":"Vista Pro Network | Real Estate | Istria | Umag Buje Novigrad Porec Rovinj","url":"https:\/\/www.vista-pro.com\/de\/","email":"info@vista-pro.com","telephone":"+385915127282","logo":{"@type":"ImageObject","url":"https:\/\/vista-pro.com\/wp-content\/uploads\/2022\/05\/logo-b.png","@id":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/#organizationLogo"},"image":{"@id":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/vistapronetwork","https:\/\/x.com\/vistapronetwork","https:\/\/instagram.com\/vistapronetwork","https:\/\/pinterest.com\/vistapronetwork","https:\/\/youtube.com\/@vistapronetwork","https:\/\/linkedin.com\/in\/vistapronetwork"],"address":{"@id":"https:\/\/www.vista-pro.com\/de\/#postaladdress","@type":"PostalAddress","streetAddress":"Vladimir Nazor 5","postalCode":"52470","addressLocality":"Umag","addressRegion":"Istria","addressCountry":"HR"},"vatID":"HR30117654631"},{"@type":"Person","@id":"https:\/\/www.vista-pro.com\/de\/author\/vista-pro\/#author","url":"https:\/\/www.vista-pro.com\/de\/author\/vista-pro\/","name":"Vista Pro"},{"@type":"WebPage","@id":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/#webpage","url":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/","name":"Stanzia Vinella in Motovun | Vista Pro | Real Estate Istria","description":"Completely secluded luxurious estate near Motovun with 60.000 m\u00b2 grounds. The farmhouse dates back to 1614 and was impeccably restored between 2019-2021.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.vista-pro.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/#breadcrumblist"},"author":{"@id":"https:\/\/www.vista-pro.com\/de\/author\/vista-pro\/#author"},"creator":{"@id":"https:\/\/www.vista-pro.com\/de\/author\/vista-pro\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/cdn.vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg?strip=all&quality=70&webp=70&avif=70&sharp=1","@id":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/#mainImage","width":2160,"height":1440},"primaryImageOfPage":{"@id":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/#mainImage"},"datePublished":"2022-11-08T01:29:41+02:00","dateModified":"2023-05-20T21:26:31+02:00"},{"@type":"WebSite","@id":"https:\/\/www.vista-pro.com\/de\/#website","url":"https:\/\/www.vista-pro.com\/de\/","name":"Vista Pro | Real Estate Istria","alternateName":"Vista Pro Network | Real Estate","description":"Vista Pro Network | Real Estate | Istria | Umag Buje Novigrad Porec Rovinj","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.vista-pro.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Vista Pro | Real Estate Istria","og:type":"article","og:title":"Stanzia Vinella in Motovun | Vista Pro | Real Estate Istria","og:description":"Completely secluded luxurious estate near Motovun with 60.000 m\u00b2 grounds. The farmhouse dates back to 1614 and was impeccably restored between 2019-2021.","og:url":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/","fb:app_id":"251215160915905","og:image":"https:\/\/vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg","og:image:secure_url":"https:\/\/vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg","og:image:width":"2160","og:image:height":"1440","article:section":"Architecture","article:tag":["architecture","istria","motovun","stanzia vinella"],"article:published_time":"2022-11-07T23:29:41+00:00","article:modified_time":"2023-05-20T19:26:31+00:00","article:publisher":"https:\/\/facebook.com\/vistapronetwork","twitter:card":"summary_large_image","twitter:site":"@vistapronetwork","twitter:title":"Stanzia Vinella in Motovun | Vista Pro | Real Estate Istria","twitter:description":"Completely secluded luxurious estate near Motovun with 60.000 m\u00b2 grounds. The farmhouse dates back to 1614 and was impeccably restored between 2019-2021.","twitter:creator":"@vistapronetwork","twitter:image":"https:\/\/vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg","twitter:label1":"Verfasst von","twitter:data1":"Vista Pro","twitter:label2":"Gesch\u00e4tzte Lesedauer","twitter:data2":"1 Minute"},"aioseo_meta_data":{"post_id":"23112","title":null,"description":"V\u00f6llig abgeschiedenes luxuri\u00f6ses Anwesen in der N\u00e4he von Motovun mit 60.000 m\u00b2 gro\u00dfem Grundst\u00fcck. Das Bauernhaus stammt aus dem Jahr 1614 und wurde zwischen 2019 und 2021 tadellos restauriert.","keywords":[],"keyphrases":{"focus":{"keyphrase":"stanzia vinella","analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":3,"maxScore":9,"error":1},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1}},"score":64},"additional":[{"keyphrase":"motovun","score":67,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"featured","og_image_url":"https:\/\/vista-pro.com\/wp-content\/uploads\/2022\/11\/stanzia-vinella-motovun-istria-croatia-real-estate-017.jpg","og_image_width":"2160","og_image_height":"1440","og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"Architecture","og_article_tags":[],"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-13 17:53:32","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2022-11-23 22:00:16","updated":"2026-05-13 17:53:32"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.vista-pro.com\/de\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">|<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.vista-pro.com\/de\/category\/istria\/\" title=\"Istria\">Istria<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">|<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.vista-pro.com\/de\/category\/istria\/motovun\/\" title=\"Motovun\">Motovun<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">|<\/span><span class=\"aioseo-breadcrumb\">\n\tStanzia Vinella in Motovun\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.vista-pro.com\/de"},{"label":"Istria","link":"https:\/\/www.vista-pro.com\/de\/category\/istria\/"},{"label":"Motovun","link":"https:\/\/www.vista-pro.com\/de\/category\/istria\/motovun\/"},{"label":"Stanzia Vinella in Motovun","link":"https:\/\/www.vista-pro.com\/de\/stanzia-vinella-in-motovun-istria-croatia-real-estate\/"}],"a3_pvc":{"activated":false,"total_views":1717,"today_views":0},"authors":[],"_links":{"self":[{"href":"https:\/\/www.vista-pro.com\/de\/wp-json\/wp\/v2\/posts\/23112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vista-pro.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vista-pro.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vista-pro.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vista-pro.com\/de\/wp-json\/wp\/v2\/comments?post=23112"}],"version-history":[{"count":0,"href":"https:\/\/www.vista-pro.com\/de\/wp-json\/wp\/v2\/posts\/23112\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vista-pro.com\/de\/wp-json\/wp\/v2\/media\/23119"}],"wp:attachment":[{"href":"https:\/\/www.vista-pro.com\/de\/wp-json\/wp\/v2\/media?parent=23112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vista-pro.com\/de\/wp-json\/wp\/v2\/categories?post=23112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vista-pro.com\/de\/wp-json\/wp\/v2\/tags?post=23112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}